{"id":43752,"date":"2026-07-15T00:00:00","date_gmt":"2026-07-14T22:00:00","guid":{"rendered":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43752\/"},"modified":"2026-07-15T12:02:19","modified_gmt":"2026-07-15T10:02:19","slug":"sjob-14280577","status":"publish","type":"job_listing","link":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43752\/","title":{"rendered":"Elektriker \/ Elektroniker \/ Mechatroniker als Monteur f\u00fcr den Neubau von Aufzugsanlagen (m\/w\/d)"},"content":{"rendered":"\n<p>Die Tepper Aufz\u00fcge GmbH ist der gr\u00f6\u00dfte Hersteller von Aufzugsanlagen in Nordrhein-Westfalen mit deutschlandweiten Standorten.<br \/>Neben dem Vertrieb, der Konstruktion, der Fertigung sowie der Montage unterschiedlichster Aufzugsanlagen, steht ein Kundendienst zur Betreuung von vorhandenen Aufzugsanlagen rund um die Uhr zur Verf\u00fcgung.<\/p> <p>Die Tepper Aufz\u00fcge GmbH ist ein TK Elevator Unternehmen.<\/p><br \/><p>Sie sind schwindelfrei und m\u00f6chten hoch hinaus?<\/p> <p>Werden Sie <strong>Aufzugstechniker (m\/w\/d)<\/strong> und gestalten Sie mit uns aktiv die Zukunft der urbanen Mobilit\u00e4t. <\/p> <ul> <li>Eigenverantwortliche Montage, Pr\u00fcfung und Inbetriebnahme unserer <strong>Aufzugsneuanlagen<\/strong><\/li> <li>Begleitung von Sachverst\u00e4ndigenpr\u00fcfungen<\/li> <li>Behebung von St\u00f6rungen<\/li> <li>\u00dcbergabe an den Kunden und Dokumentation der Arbeiten<\/li> <li>Laufende Qualit\u00e4tskontrolle und -sicherung der Anlagen<\/li> <\/ul><br \/><ul> <li>Abgeschlossene Berufsausbildung der Fachrichtung Mechatronik, Elektronik, Elektrotechnik, Elektrik oder vergleichbar<\/li> <li>Idealerweise Kenntnisse im elektrotechnischen Umfeld sowie im Bereich Steuerungs- und Regeltechnik<\/li> <li>Ausgepr\u00e4gte Kundenorientierung, Zuverl\u00e4ssigkeit sowie Einsatzbereitschaft<\/li> <li>Teamf\u00e4higkeit und Leidenschaft im Umgang mit moderner Technik<\/li> <li>Gute Deutsch-Kenntnisse in Wort und Schrift<\/li> <li>F\u00fchrerschein Klasse B und Wohnort im unmittelbaren Einsatzgebiet<\/li> <\/ul> <p>Um den Bewerbungsprozess zu beschleunigen, f\u00fcgen Sie bitte Ihrer Bewerbung Ihre Ausbildungszeugnisse (z. B. IHK oder vergleichbare Einrichtungen) bei.<\/p><br \/><ul> <li><strong>Faire Verg\u00fctung &#038; Zukunftssicherung<\/strong>: Profitieren Sie von einem transparenten Gehalt gem\u00e4\u00df dem Metall- und Elektro-Tarifvertrag Nordrhein-Westfalen inkl. Urlaubs- und Weihnachtsgeld sowie tariflichen Sonderzahlungen. Dazu: Ausl\u00f6se und attraktive Modelle zur Altersvorsorge f\u00fcr Ihre finanzielle Absicherung<\/li> <li><strong>Flexible Arbeitswelt &#038; Balance: <\/strong>Profitieren Sie von flexiblen Arbeitszeiten bei einer 35-Stundenwoche mit wohnortnahmen Einsatzgebiet &#038; 30 Tagen Urlaub \u2013 f\u00fcr eine perfekte Balance zwischen Job und Freizeit<\/li> <li><strong>Ausstattung, die begeistert<\/strong>: Starten Sie durch mit erstklassiger Ausstattung, inklusive Tablet\/Smartphone, einem Firmenwagen mit Option auf Privatnutzung sowie moderner Arbeitskleidung und Werkzeugen \u2013 f\u00fcr maximale Effizienz und Komfort<\/li> <li><strong>Entwicklung mit Vision<\/strong>: Entfalten Sie Ihr volles Potential durch Zugang zu interessanten Trainingsangeboten, E-Learning sowie exklusiven Talentprogrammen<\/li> <li><strong>Gesundheit &#038; Gl\u00fcck<\/strong>: Profitieren Sie von Kinderbetreuungs- und Pflegeberatungs-Unterst\u00fctzung, Zuschuss zur Ern\u00e4hrungsberatung sowie Programmen zur Stressbew\u00e4ltigung und vertraulicher Mitarbeitendenberatung<\/li> <li><strong>Nachhaltig mobil: <\/strong>Nutzen Sie das BusinessBike-Angebot oder den Zuschuss zum Deutschlandticket f\u00fcr eine umweltfreundliche und flexible Mobilit\u00e4t<\/li> <li><strong>Verantwortung &#038; Engagement: <\/strong>Engagieren Sie sich mit uns bei den SOS-Kinderd\u00f6rfern und in der Katastrophenhilfe, seien Sie Teil unseres Beitrags zum UN Global Compact, unterst\u00fctzen Sie unsere Mission zur CO2-Neutralit\u00e4t und f\u00f6rdern Sie aktiv Vielfalt und Inklusion<\/li> <\/ul> <br \/> Wir wertsch\u00e4tzen Vielfalt <br \/><br \/> <p>Wir wollen uns die Vielfalt zu eigen machen und hei\u00dfen jeden willkommen \u2013 unabh\u00e4ngig von ethnischer Zugeh\u00f6rigkeit, Nationalit\u00e4t, Geschlecht oder Geschlechtsausdruck, Alter, sozialer Herkunft, Religion oder Weltanschauung, sexueller Orientierung, Behinderung, Familienstand oder anderen gesetzlich gesch\u00fctzten Eigenschaften oder Status.<\/p> <p>Sie haben eine Behinderung und m\u00f6chten gerne bei uns arbeiten? Dann freuen wir uns auf Ihre Bewerbung!<\/p> <p>Als Unterzeichner der Charta der Vielfalt engagieren wir uns f\u00fcr ein vorurteilsfreies und vielf\u00e4ltiges Arbeitsumfeld mit Chancengleichheit. Obwohl wir noch nicht vollst\u00e4ndig barrierefrei sind, arbeiten wir jeden Tag daran, uns f\u00fcr Sie zu verbessern. Lassen Sie uns gemeinsam Barrieren \u00fcberwinden und an individuellen L\u00f6sungen arbeiten, die zu Ihnen passen.<\/p>\n","protected":false},"author":2,"featured_media":6263,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"yes","_seopress_robots_snippet":"yes","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_job_source":"stepstone","_promoted":"","_job_location":"Berlin","_application":"https:\/\/www.stepstone.de\/stellenangebote--elektriker-elektroniker-mechatroniker-als-monteur-fuer-den-neubau-von-aufzugsanlagen-m-w-d-berlin-tepper-aufzuege-gmbh-ein-tk-elevator-unternehmen--14280577-inline.html?&cid=partner_krafthand___SP&adjust_t=1bbth7ql_1bjy99sm&adjust_campaign=partner_krafthand___SP","_company_name":"Tepper Aufz\u00fcge GmbH - Ein TK Elevator Unternehmen","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[9],"job_listing_statue":[13],"job_listing_experience":[14],"class_list":["post-43752","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_type-vollzeit","job_listing_statue-feste-anstellung","job_listing_experience-mit-berufserfahrung","job-type-vollzeit","job_listing_stepstone"],"_links":{"self":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings\/43752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media\/6263"}],"wp:attachment":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media?parent=43752"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-types?post=43752"},{"taxonomy":"job_listing_statue","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_statue?post=43752"},{"taxonomy":"job_listing_experience","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_experience?post=43752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}