{"id":43732,"date":"2026-07-14T00:00:00","date_gmt":"2026-07-13T22:00:00","guid":{"rendered":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43732\/"},"modified":"2026-07-15T20:10:20","modified_gmt":"2026-07-15T18:10:20","slug":"sjob-14277943","status":"publish","type":"job_listing","link":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43732\/","title":{"rendered":"Mechatroniker f\u00fcr K\u00e4ltetechnik \/ K\u00e4lteanlagenbauer m\/w\/d"},"content":{"rendered":"\n<p>Bonjour, Servus, Gr\u00fcezi und Hallo, wir sind SPIE Germany Switzerland Austria. Wir &#8211; das sind 20.000 Technikbegeisterte an 250 Standorten in Deutschland, der Schweiz, \u00d6sterreich und dar\u00fcber hinaus, die sich gemeinsam mit unseren Kunden f\u00fcr eine klimafreundliche und digitale Zukunft stark machen. Mit unserer umfassenden Expertise und Begeisterung f\u00fcr technische Dienstleistung geben wir das Beste f\u00fcr unsere Kunden &#8211; jeden Tag, in jedem Projekt.<\/p>  <p>SPIE Germany Switzerland Austria ist eine Unternehmenseinheit der SPIE Gruppe, dem unabh\u00e4ngigen europ\u00e4ischen Marktf\u00fchrer f\u00fcr multitechnische Dienstleistungen in den Bereichen Energie und Kommunikation. Mehr dazu: \u00dcber uns<\/p>  <p>Du brennst f\u00fcr moderne Klimatechnik und suchst eine langfristige Perspektive in einem krisensicheren Umfeld? Als Mechatroniker f\u00fcr K\u00e4ltetechnik m\/w\/d \u00fcbernimmst Du bei SPIE die fachgerechte Betreuung geb\u00e4udetechnischer Anlagen in abwechslungsreichen Industrie- und B\u00fcrogeb\u00e4uden. Nutze Deine Expertise im Service und in der Instandhaltung, profitiere von individuellen Entwicklungsm\u00f6glichkeiten und werde Teil eines starken, technikbegeisterten Teams.<\/p>  <h2>Mechatroniker f\u00fcr K\u00e4ltetechnik \/ K\u00e4lteanlagenbauer m\/w\/d<\/h2>       <p>Einsatzort: K\u00f6ln<br \/> Kennziffer: 2026-0158<br \/> Arbeitszeit: Vollzeit<\/p><br \/><ul><li>Umfassende k\u00e4ltetechnische Betreuung von modernen Industrie- und B\u00fcrogeb\u00e4uden im Raum K\u00f6ln<\/li><\/ul><ul><li>Fachgerechte Wartung und Instandsetzung von Klimager\u00e4ten (Split\/VRF), Kaltwassererzeugern und gewerblichen K\u00e4lteanlagen<\/li><\/ul><ul><li>Selbstst\u00e4ndige Behebung von St\u00f6rungen an den Systemen und nachhaltige Optimierung der Betriebsabl\u00e4ufe<\/li><\/ul><br \/><ul><li>Abgeschlossene technische Ausbildung z.B. als Mechatroniker f\u00fcr K\u00e4ltetechnik \/ K\u00e4lteanlagenbauer \/ Anlagenmechaniker HKLS oder Zentralheizungs- und L\u00fcftungsbauer<\/li><\/ul><ul><li>Idealerweise mehrj\u00e4hrige Berufserfahrung in einer vergleichbaren Position, wobei engagierte Berufseinsteigende mit Fortbildungsambitionen ebenfalls herzlich willkommen sind<\/li><\/ul><ul><li>W\u00fcnschenswert sind fundierte Erfahrungen in der K\u00e4ltetechnik und der Instandhaltung von Kaltwassererzeugern im Bereich von \u00fcber 100 kW k\u00e4ltetechnischer Leistung<\/li><\/ul><ul><li>G\u00fcltige Sachkundebescheinigung nach \u00a7 5 ChemKlimaschutzVO Kategorie 1 von Vorteil<\/li><\/ul><ul><li>Serviceorientiertes Auftreten, eine selbstst\u00e4ndige Arbeitsweise sowie ausgepr\u00e4gte Teamf\u00e4higkeit<\/li><\/ul><ul><li>Flie\u00dfende Deutschkenntnisse auf C1-Niveau sowie ein F\u00fchrerschein der Klasse B<\/li><\/ul><br \/><ul><li>Eigenes Servicefahrzeug<\/li><li>Haustarif mit fairer Bezahlung, \u00dcberstundenausgleich, etc.<\/li><li>Anteiliges 13. Monatseinkommen<\/li><li>Unbefristeter Arbeitsvertrag in einer krisensicheren Branche<\/li><li>Bis zu 35 Tage Urlaub<\/li><li>Flexible Arbeitszeiten zur Vereinbarkeit von Familie, Freunden und Beruf<\/li><li>Professionelles Werkzeug und moderne Arbeitskleidung \/ PSA<\/li><li>Mitarbeiterempfehlungsprogramm mit Pr\u00e4mien bis zu \u20ac 2.550<\/li><li>Unterst\u00fctzungsfonds hilft in schwierigen Lebenslagen &#8211; freiwillige Rest-Cent-Spende deiner Nettoverg\u00fctung<\/li><li>Attraktives Mitarbeiter-Aktienbeteiligungsprogramm<\/li><li>Individuelle Weiterbildungsm\u00f6glichkeiten \u00fcber die SPIE Akademie<\/li><li>Jobrad-Leasing<\/li><li>Corporate Benefits \u2013 Rabatte bei vielen Marken und Shops<\/li><\/ul>     <p>Klingt nach Deinem n\u00e4chsten Karriereschritt? Dann freuen wir uns darauf, Dich kennenzulernen. Bewirb Dich jetzt und werde Teil des SPIE Teams!<\/p>\n","protected":false},"author":2,"featured_media":6139,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"yes","_seopress_robots_snippet":"yes","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_job_source":"stepstone","_promoted":"","_job_location":"K\u00f6ln","_application":"https:\/\/www.stepstone.de\/stellenangebote--mechatroniker-fuer-kaeltetechnik-kaelteanlagenbauer-m-w-d-koeln-spie-efficient-facilities-gmbh--14277943-inline.html?&cid=partner_krafthand___SP&adjust_t=1bbth7ql_1bjy99sm&adjust_campaign=partner_krafthand___SP","_company_name":"SPIE Efficient Facilities GmbH","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[9],"job_listing_statue":[20,13],"job_listing_experience":[14,12],"class_list":["post-43732","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_type-vollzeit","job_listing_statue-berufseinstieg-trainee","job_listing_statue-feste-anstellung","job_listing_experience-mit-berufserfahrung","job_listing_experience-ohne-berufserfahrung","job-type-vollzeit","job_listing_stepstone"],"_links":{"self":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings\/43732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media\/6139"}],"wp:attachment":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media?parent=43732"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-types?post=43732"},{"taxonomy":"job_listing_statue","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_statue?post=43732"},{"taxonomy":"job_listing_experience","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_experience?post=43732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}