{"id":43691,"date":"2026-07-14T00:00:00","date_gmt":"2026-07-13T22:00:00","guid":{"rendered":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43691\/"},"modified":"2026-07-15T20:16:07","modified_gmt":"2026-07-15T18:16:07","slug":"sjob-14275798","status":"publish","type":"job_listing","link":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43691\/","title":{"rendered":"Mechatroniker (m\/w\/d)"},"content":{"rendered":"\n<p>Gestalten Sie Ihren beruflichen Weg neu \u2013 bei unserem Gesch\u00e4ftspartner in Frankenberg (Eder) als Elektromechaniker. Bewerben Sie sich online und sichern Sie sich die Chance auf einen neuen attraktiven Job. Wir sind \u00fcberzeugt, dass Vielfalt neue Ideen hervorbringt. Bringen Sie Ihre einzigartigen F\u00e4higkeiten ein. Randstad ist Ihr starker Partner f\u00fcr Ihre Karriere. Wir sind f\u00fcr Sie da, wann immer Sie uns brauchen.<\/p><br \/><ul> <li>Produktion von Bauteilen<\/li> <li>Anlagenmontage<\/li> <li>Softwareinstallation<\/li> <li>Fehlerbehebung<\/li> <\/ul><br \/><ul> <li>Abgeschlossene Ausbildung als Mechatroniker, Industrieelektroniker oder BMSR-Mechaniker<\/li> <li>Erfahrung im Umgang mit SPS und ggf. in der Programmierung<\/li> <li>Bereitschaft zur Schichtarbeit (3-Schicht)<\/li> <li>F\u00fchrerschein Klasse B und Pkw von Vorteil<\/li> <\/ul><br \/><p>\u25cf Extra Zulagen bei langfristigen Eins\u00e4tzen<br \/> \u25cf Kompetente Ansprechpartner vor Ort<br \/> \u25cf Monatlich wechselnde Rabattaktionen, z.B. f\u00fcr Sportbekleidung, Kosmetik, Schuhe und vieles mehr<br \/> \u25cf Zus\u00e4tzlich 250 \u20ac (brutto) f\u00fcr jede erfolgreiche Weiterempfehlung an einen Freund oder Bekannten<br \/> \u25cf Interessenvertretung durch einen fl\u00e4chendeckenden Betriebsrat<\/p>\n","protected":false},"author":2,"featured_media":8194,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"yes","_seopress_robots_snippet":"yes","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_job_source":"stepstone","_promoted":"","_job_location":"Frankenberg (Eder)","_application":"https:\/\/www.stepstone.de\/stellenangebote--mechatroniker-m-w-d-frankenberg-eder-randstad-deutschland-gmbh-co-kg--14275798-inline.html?&cid=partner_krafthand___SP&adjust_t=1bbth7ql_1bjy99sm&adjust_campaign=partner_krafthand___SP","_company_name":"Randstad Deutschland GmbH & Co. KG","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[],"job_listing_statue":[],"job_listing_experience":[],"class_list":["post-43691","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_stepstone"],"_links":{"self":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings\/43691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media\/8194"}],"wp:attachment":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media?parent=43691"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-types?post=43691"},{"taxonomy":"job_listing_statue","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_statue?post=43691"},{"taxonomy":"job_listing_experience","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_experience?post=43691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}