{"id":43666,"date":"2026-07-13T00:00:00","date_gmt":"2026-07-12T22:00:00","guid":{"rendered":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43666\/"},"modified":"2026-07-15T12:17:23","modified_gmt":"2026-07-15T10:17:23","slug":"sjob-14274647","status":"publish","type":"job_listing","link":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/43666\/","title":{"rendered":"Industriemechaniker \/ Mechatroniker (m\/w\/d)"},"content":{"rendered":"\nF\u00fcr einen international agierenden Betrieb aus dem Maschinenbau f\u00fcr Abf\u00fcll- und Verpackungsanlagen (Streckblasmaschinen), mit einer sehr guten Verkehrsanbindung im \u00f6stlichen Hamburg (Grenze zu Ahrensburg), suchen wir schnellstm\u00f6glich mehrere<br \/> <br \/> <strong>Maschinenbaumechaniker (m\/w\/d), Industriemechaniker (m\/w\/d), Baugruppenmonteure (m\/w\/d) Mechatroniker (m\/w\/d)<\/strong> o.\u00e4. in <strong>Vollzeit.<\/strong><br \/> <br \/> Der traditionelle Maschinenbauer ist schon \u00fcber 50 Jahre am Standort Hamburg.<br \/> Das Unternehmen hat sich st\u00e4ndig weiterentwickelt und arbeitet nach h\u00f6chsten ergonomischen Standards um Mitarbeitern die Arbeit zu erleichtern und z.B. Zwangshaltungen zu vermeiden, zu schwere Lasten manuell heben zu m\u00fcssen etc.<br \/> Eine \u00dcbernahme in den Kundenbetrieb ist bei Eignung m\u00f6glich.<br \/> <br \/> <strong>>> Lohnentwicklung nach Branchenzuschlag<\/strong><br \/><br \/><ul><li>Die Montage von komplexen Baugruppen und Modulen nach technischen Zeichnungen und St\u00fccklisten geh\u00f6rt zu Ihren Hauptaufgaben.<\/li><li>Sie Vermessen s\u00e4mtliche Pr\u00fcfvorgaben.<\/li><li>Sie arbeiten unter Einhaltung der KHSps Systeme und Vorgaben (z.B. Ordnung, Sauberkeit, 5S und 7P).<\/li><\/ul><br \/><br \/><ul><li>Sie verf\u00fcgen \u00fcber eine abgeschlossene Berufsausbildung zum Industriemechaniker, Maschinenbaumechaniker, KfZ-Mechatroniker \u00f6.\u00e4.denkbar w\u00e4re auch eine Besch\u00e4ftigung ohne Ausbildung daf\u00fcr aber mit Berufserfahrung in der Baugruppenmontage.<\/li><li>Handwerkliches Geschick, technisches Verst\u00e4ndnis und Spa\u00df am &#8222;Schrauben&#8220; zeichnet Sie aus.<\/li><li>Gute deutsche Sprachkenntnisse, P\u00fcnktlichkeit und ein hohes Qualit\u00e4tsbewusstsein sind f\u00fcr Sie selbstverst\u00e4ndlich.<\/li><\/ul><br \/><br \/><ul><li>Wir zahlen ein tarifliches Gehalt, Branchenzuschl\u00e4ge sowie <strong>Urlaubs- und Weihnachtsgeld<\/strong> nach den Vorgaben des Bundesverbands f\u00fcr Personaldienstleister (BAP).<\/li><li>HVV Profi-Card \/ Deutschlandticket<\/li><li>Ein Betriebsparkplatz steht zur Verf\u00fcgung<\/li><li>Mitarbeiter erhalten eine <strong>Profi-Ausstattung<\/strong> an Schutz- und Arbeitskleidung und medizinische Vorsorge durch das Werksarztzentrum.<\/li><li>Bei uns erhalten Mitarbeiter Pr\u00e4mien zu besonderen Anl\u00e4ssen sowie exklusive Rabatte in \u00fcber 600 Gesch\u00e4ften und Online-Shops.<\/li><li>Zum pr\u00e4ventiven Gesundheitsschutz stellen wir Gesundheitsmasken zur Verf\u00fcgung.<\/li><li>Mit der expertum JobApp kommunizieren Mitarbeiter direkt mit dem Ansprechpartner und verwalten das Zeitkonto in der App.<\/li><li>Bei Bedarf finanzieren wir <strong>individuelle Fortbildungen<\/strong>, die Mitarbeiter langfristig weiterbringen.<\/li><li>In Kooperation mit der Allianz und der N\u00fcrnberger Versicherung bieten wir eine betriebliche Altersvorsorge.<\/li><li>Auch zu anderen ausgeschriebenen Stellen und Karrierem\u00f6glichkeiten beraten wir jederzeit gern.<\/li><\/ul>\n","protected":false},"author":2,"featured_media":6002,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"yes","_seopress_robots_snippet":"yes","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_job_source":"stepstone","_promoted":"","_job_location":"Hamburg","_application":"https:\/\/www.stepstone.de\/stellenangebote--industriemechaniker-mechatroniker-m-w-d-hamburg-expertum-gmbh--14274647-inline.html?&cid=partner_krafthand___SP&adjust_t=1bbth7ql_1bjy99sm&adjust_campaign=partner_krafthand___SP","_company_name":"expertum GmbH","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[],"job_listing_statue":[],"job_listing_experience":[],"class_list":["post-43666","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_stepstone"],"_links":{"self":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings\/43666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media\/6002"}],"wp:attachment":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media?parent=43666"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-types?post=43666"},{"taxonomy":"job_listing_statue","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_statue?post=43666"},{"taxonomy":"job_listing_experience","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_experience?post=43666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}