{"id":42925,"date":"2026-07-04T00:00:00","date_gmt":"2026-07-03T22:00:00","guid":{"rendered":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/42925\/"},"modified":"2026-07-15T13:36:23","modified_gmt":"2026-07-15T11:36:23","slug":"sjob-14221110","status":"publish","type":"job_listing","link":"https:\/\/www.krafthand.de\/stellenmarkt\/inserat\/42925\/","title":{"rendered":"Serviceberater Nutzfahrzeuge (m\/w\/d)"},"content":{"rendered":"\n<p>Abwechslungsreich, digital und fortschrittlich: So arbeiten wir in der <strong>FRICKE Gruppe<\/strong>. Mit \u00fcber 4.000 Mitarbeitenden &#8211; verteilt auf 107 Standorte in 28 L\u00e4ndern \u2013 ist unser gemeinsames Ziel, unseren Kunden hochwertige Ersatzteile, hervorragende Maschinen und erstklassigen Service zu bieten. Unser Erfolg beruht auf unserem starken Team. Als Familienunternehmen mit mehr als 100 Jahren Erfahrung entwickeln wir uns st\u00e4ndig weiter.<br \/> <br \/> <strong>FRICKE Nutzfahrzeuge<\/strong> geh\u00f6rt als Teil der FRICKE Gruppe zu den gr\u00f6\u00dften Handels- und Servicepartnern von DAF TRUCKS, FIAT Professional, SCANIA und ISUZU in Deutschland. An unseren sechs Standorten in Norddeutschland bieten wir unseren Kunden kompetente Beratung sowie umfassende, fabrikatsunabh\u00e4ngige Wartungs- und Reparaturservices.<\/p>  <p><strong>GROW WITH US. <\/strong>Wir suchen Sie zur Erweiterung unseres Teams am Standort <strong>Bad Fallingbostel<\/strong> (Gustaf-de-Laval-Str. 9, 29683 Bad Fallingbostel) als<\/p>  <p><strong>Serviceberater Nutzfahrzeuge (m\/w\/d)<\/strong><\/p><br \/><ul>  <li><strong>Fahrzeugannahmen durchf\u00fchren:<\/strong> Annahme der Fahrzeuge gemeinsam mit unseren Kunden<\/li>  <li><strong>Werkstattkapazit\u00e4ten planen:<\/strong> Organisation der Auslastung und Einteilung der Auftr\u00e4ge<\/li>  <li><strong>Auftr\u00e4ge erfassen:<\/strong> Aufnahme detaillierter Auftr\u00e4ge mit allen erforderlichen Daten<\/li>  <li><strong>Preis- und Terminzusagen geben:<\/strong> Verbindliche Zusagen an unsere Kunden erteilen<\/li>  <li><strong>Zur\u00fcstungen abstimmen:<\/strong> Planung von Zur\u00fcstungsarbeiten an Neufahrzeugen in Abstimmung mit dem Vertrieb und unseren Kunden<\/li>  <li><strong>Freigaben einholen:<\/strong> Organisation von Zahlungsfreigaben und Auftragserweiterungen<\/li>  <li><strong>Technische Fragen kl\u00e4ren:<\/strong> Kontaktaufnahme mit den Herstellern f\u00fcr technischen Support<\/li> <\/ul><br \/><ul>  <li><strong>Ausbildung &#038; Qualifikation: <\/strong>Erfolgreich abgeschlossene technische oder kaufm\u00e4nnisch-technische Berufsausbildung, beispielsweise als KFZ-Mechatroniker \/ Nutzfahrzeugmechatroniker (m\/w\/d), KFZ-\/NFZ-Mechaniker (m\/w\/d) oder Automobilkaufmann (m\/w\/d) mit Weiterbildung zum KFZ-\/NFZ-Meister (m\/w\/d)<\/li>  <li><strong>Berufserfahrung &#038; Fachwissen:<\/strong> Berufserfahrung in einer vergleichbaren Position w\u00fcnschenswert \u2013 idealerweise mit Praxiserfahrung im Nutzfahrzeug-Umfeld<\/li>  <li><strong>IT- &#038; Sprachkenntnisse:<\/strong> Sicherer Umgang mit g\u00e4ngigen Office-Programmen<\/li>  <li><strong>Pers\u00f6nliche Kompetenz: <\/strong>Selbstst\u00e4ndige und kundenorientierte Arbeitsweise sowie Kommunikationsst\u00e4rke<\/li> <\/ul><br \/><ul>  <li><strong>Ihr Start bei FRICKE: <\/strong>Eine strukturierte Einarbeitung mit fester Ansprechperson sorgt f\u00fcr einen erfolgreichen Start. Sie werden im Team herzlich aufgenommen und erhalten von Anfang an die Unterst\u00fctzung, die Sie brauchen.<\/li>  <li><strong>Moderne Arbeitswelt:<\/strong> Freuen Sie sich auf moderne Arbeitspl\u00e4tze und flache Hierarchien. Bei uns wird auf Augenh\u00f6he kommuniziert \u2013 Entscheidungen treffen wir schnell und gemeinsam. Dar\u00fcber hinaus profitieren Sie von flexiblen Arbeitszeiten im Rahmen der betrieblichen Abl\u00e4ufe.<\/li>  <li><strong>Stabiles Fundament: <\/strong>30 Tage Urlaub, Urlaubs- und Weihnachtsgeld, verm\u00f6genswirksame Leistungen und j\u00e4hrliche Gehaltsanpassungen bieten Ihnen eine verl\u00e4ssliche Grundlage und Anerkennung Ihrer Leistung.<\/li>  <li><strong>Entwicklung f\u00f6rdern:<\/strong> Wir bieten Ihnen interne und externe Schulungen und Weiterbildungsm\u00f6glichkeiten, um Ihre fachliche und pers\u00f6nliche Entwicklung individuell zu unterst\u00fctzen.<\/li>  <li><strong>Ihr Wohlbefinden z\u00e4hlt:<\/strong> Ein gesundes Arbeitsumfeld ist f\u00fcr uns selbstverst\u00e4ndlich. Dazu z\u00e4hlen nicht nur ergonomische Arbeitspl\u00e4tze und das JobRad-Leasing, sondern vor allem ein respektvolles, unterst\u00fctzendes Miteinander, in dem Sie sich entfalten k\u00f6nnen.<\/li>  <li><strong>Gemeinsam mehr erleben:<\/strong> Ob einzigartige Mitarbeiterevents wie unser Firmenfestival HEAT WAVE oder gemeinsame sportliche Aktivit\u00e4ten beim FRICKE Social Run: Bei uns wird das Miteinander gelebt \u2013 denn gute Zusammenarbeit beginnt mit einer starken Gemeinschaft.<\/li> <\/ul>\n","protected":false},"author":2,"featured_media":21268,"template":"","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"yes","_seopress_robots_snippet":"yes","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_job_source":"stepstone","_promoted":"","_job_location":"Bad Fallingbostel bei Walsrode","_application":"https:\/\/www.stepstone.de\/stellenangebote--serviceberater-nutzfahrzeuge-m-w-d-bad-fallingbostel-bei-walsrode-fricke-nutzfahrzeuge-gmbh--14221110-inline.html?&cid=partner_krafthand___SP&adjust_t=1bbth7ql_1bjy99sm&adjust_campaign=partner_krafthand___SP","_company_name":"FRICKE Nutzfahrzeuge GmbH","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[9],"job_listing_statue":[13],"job_listing_experience":[14],"class_list":["post-42925","job_listing","type-job_listing","status-publish","has-post-thumbnail","hentry","job_listing_type-vollzeit","job_listing_statue-feste-anstellung","job_listing_experience-mit-berufserfahrung","job-type-vollzeit","job_listing_stepstone"],"_links":{"self":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings\/42925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media\/21268"}],"wp:attachment":[{"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/media?parent=42925"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job-types?post=42925"},{"taxonomy":"job_listing_statue","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_statue?post=42925"},{"taxonomy":"job_listing_experience","embeddable":true,"href":"https:\/\/www.krafthand.de\/stellenmarkt\/wp-json\/wp\/v2\/job_listing_experience?post=42925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}